{"id":2263,"date":"2022-11-29T15:42:35","date_gmt":"2022-11-29T20:42:35","guid":{"rendered":"https:\/\/iesjuli.edu.pe\/portal\/?page_id=2263"},"modified":"2025-06-27T10:52:40","modified_gmt":"2025-06-27T15:52:40","slug":"desarrollo-pesquero-y-acuicola","status":"publish","type":"page","link":"https:\/\/iesjuli.edu.pe\/portal\/desarrollo-pesquero-y-acuicola\/","title":{"rendered":"Desarrollo Pesquero y Acu\u00edcola"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2263\" class=\"elementor elementor-2263\">\n\t\t\t\t\t\t<section class=\"default no-position elementor-section elementor-top-section elementor-element elementor-element-4d47ccc elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"4d47ccc\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a61c520\" data-id=\"a61c520\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96e2790 elementor-widget elementor-widget-eael-adv-tabs\" data-id=\"96e2790\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"eael-adv-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div data-scroll-on-click=\"no\" data-scroll-speed=\"300\" id=\"eael-advance-tabs-96e2790\" class=\"eael-advance-tabs eael-tabs-horizontal eael-tab-auto-active \" data-tabid=\"96e2790\">\n            <div class=\"eael-tabs-nav\">\n                <ul class=\"eael-tab-inline-icon\" role=\"tablist\">\n                                            <li id=\"descripcin-general\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"descripcin-general-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"far fa-file-image\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Descripci\u00f3n General<\/span>                            \n                                                    <\/li>\n                                            <li id=\"mdulos-y-certificaciones\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"mdulos-y-certificaciones-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"far fa-address-card\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >M\u00f3dulos y Certificaciones<\/span>                            \n                                                    <\/li>\n                                            <li id=\"unidades-didcticas\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"unidades-didcticas-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-book-open\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Unidades Did\u00e1cticas<\/span>                            \n                                                    <\/li>\n                                            <li id=\"itinerario-formativo\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"itinerario-formativo-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-list-alt\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Itinerario Formativo<\/span>                            \n                                                    <\/li>\n                                            <li id=\"horario-de-actividades\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"horario-de-actividades-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"far fa-calendar-alt\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Horario de Actividades<\/span>                            \n                                                    <\/li>\n                                            <li id=\"perfil-de-egreso\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"perfil-de-egreso-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-graduation-cap\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >Perfil de Egreso<\/span>                            \n                                                    <\/li>\n                                    <\/ul>\n            <\/div>\n            \n            <div class=\"eael-tabs-content\">\n\t\t        \n                    <div id=\"descripcin-general-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"descripcin-general-tab\">\n\t\t\t\t        <p><span style=\"color: #000080;\"><strong>COMPETENCIAS ESPEC\u00cdFICAS:<\/strong><\/span><\/p><ol><li><span style=\"color: #000080;\">Administrar los recursos requeridos en la unidad de embarcaci\u00f3n, de acuerdo con el tipo de especie a capturar, habitad acu\u00e1tico, embarcaci\u00f3n y normativa correspondiente.<\/span><\/li><li><span style=\"color: #000080;\">Controlar par\u00e1metros del aspecto ambiental, de seguridad e inocuidad de los procesos y actividades de pesca, de acuerdo con los sistemas integrados de gesti\u00f3n, est\u00e1ndares y normativa correspondiente.<\/span><\/li><li><span style=\"color: #000080;\">Dirigir las actividades de pesca de acuerdo con las funciones de la tripulaci\u00f3n, preservaci\u00f3n del recurso, \u00e1mbito acu\u00e1tico, seguridad de la embarcaci\u00f3n y normativa correspondiente.<\/span><\/li><li><span style=\"color: #000080;\">Implementar la infraestructura acu\u00edcola de acuerdo con las tecnolog\u00edas de cultivo, h\u00e1bitat acu\u00e1tico, condiciones sanitarias de las especies hidrobiol\u00f3gicas y normativa correspondiente.<\/span><\/li><li><span style=\"color: #000080;\">Supervisar las actividades acu\u00edcolas de acuerdo con las tecnolog\u00edas, especies hidrobiol\u00f3gicas, procedimientos establecidos y normativa correspondiente.<\/span><\/li><li><span style=\"color: #000080;\">Ejecutar el tipo de procesamiento del recurso hidrobiol\u00f3gico e insumos de acuerdo con el m\u00e9todo o tipo de operaci\u00f3n seleccionada, procedimientos establecidos y normativa correspondiente.<\/span><\/li><li><span style=\"color: #000080;\">Ejecutar las operaciones de envasado, empaque y almacenamiento de los productos hidrobiol\u00f3gicos, piensos y producto veterinario de uso en acuicultura considerando su trazabilidad, requerimientos tecnol\u00f3gicos del cliente, procedimientos establecidos y normativa correspondiente.<\/span><\/li><li><span style=\"color: #000080;\">Establecer la log\u00edstica de distribuci\u00f3n de mercanc\u00edas considerando la cadena de fr\u00edo, puntos de comercializaci\u00f3n y normativa correspondiente.<\/span><\/li><\/ol><p><span style=\"color: #000080;\"><strong>T\u00cdTULO A NOMBRE DE LA NACI\u00d3N:<\/strong><\/span><\/p><ul><li><span style=\"color: #000080;\">Profesional T\u00e9cnico en Desarrollo Pesquero y Acu\u00edcola<\/span><\/li><\/ul><p><span style=\"color: #000080;\"><strong>DURACI\u00d3N DE ESTUDIOS:<\/strong><\/span><\/p><ul><li><span style=\"color: #000080;\">03 a\u00f1os (06 semestres acad\u00e9micos)<\/span><\/li><\/ul><p><span style=\"color: #000080;\"><strong>MODALIDAD DE SERVICIO:<\/strong><\/span><\/p><ul><li><span style=\"color: #000080;\">Presencial.<\/span><\/li><\/ul>                    <\/div>\n\t\t        \n                    <div id=\"mdulos-y-certificaciones-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"mdulos-y-certificaciones-tab\">\n\t\t\t\t        <h4>CERTIFICACIONES POR CADA M\u00d3DULO PROFESIONAL<\/h4><table><tbody><tr><th>CERTIFICADO<\/th><th>DENOMINACI\u00d3N DEL M\u00d3DULO<\/th><th>DURACI\u00d3N<\/th><th>SEMESTRE<\/th><\/tr><tr><td rowspan=\"2\"><center><img decoding=\"async\" src=\"https:\/\/iesjuli.edu.pe\/portal\/wp-content\/uploads\/2024\/10\/CERTIFICADO-MODULAR.png\" width=\"180px\" height=\"50\" \/><\/center><\/td><td>M\u00f3dulo N\u00b0 01: Implementaci\u00f3n y supervisi\u00f3n de sistemas de producci\u00f3n acu\u00edcola.<\/td><td style=\"text-align: center;\">960 Horas<\/td><td style=\"text-align: center;\" rowspan=\"2\">I, II<\/td><\/tr><tr><td>EFSRT 01: Experiencias Formativas en Situaciones Reales de Trabajo<\/td><td style=\"text-align: center;\">128 Horas<\/td><\/tr><tr><td rowspan=\"2\"><center><img decoding=\"async\" src=\"https:\/\/iesjuli.edu.pe\/portal\/wp-content\/uploads\/2024\/10\/CERTIFICADO-MODULAR.png\" width=\"180px\" height=\"50\" \/><\/center><\/td><td>M\u00f3dulo N\u00b0 02: Administraci\u00f3n de recursos y direcci\u00f3n de actividades de pesca.<\/td><td style=\"text-align: center;\">480 Horas<\/td><td style=\"text-align: center;\" rowspan=\"2\">III<\/td><\/tr><tr><td>EFSRT 02: Experiencias Formativas en Situaciones Reales de Trabajo<\/td><td style=\"text-align: center;\">64 Horas<\/td><\/tr><tr><td rowspan=\"2\"><center><img decoding=\"async\" src=\"https:\/\/iesjuli.edu.pe\/portal\/wp-content\/uploads\/2024\/10\/CERTIFICADO-MODULAR.png\" width=\"180px\" height=\"50\" \/><\/center><\/td><td>M\u00f3dulo N\u00b0 03: Control y log\u00edstica pesquera.<\/td><td style=\"text-align: center;\">480 Horas<\/td><td style=\"text-align: center;\" rowspan=\"2\">IV<\/td><\/tr><tr><td>EFSRT 03: Experiencias Formativas en Situaciones Reales de Trabajo<\/td><td style=\"text-align: center;\">64 Horas<\/td><\/tr><tr><td rowspan=\"2\"><center><img decoding=\"async\" src=\"https:\/\/iesjuli.edu.pe\/portal\/wp-content\/uploads\/2024\/10\/CERTIFICADO-MODULAR.png\" width=\"180px\" height=\"50\" \/><\/center><\/td><td>M\u00f3dulo N\u00b0 04: Procesamiento y envasado de productos hidrobiol\u00f3gicos.<\/td><td style=\"text-align: center;\">960 Horas<\/td><td style=\"text-align: center;\" rowspan=\"2\">V, VI<\/td><\/tr><tr><td>EFSRT 04: Experiencias Formativas en Situaciones Reales de Trabajo<\/td><td style=\"text-align: center;\">128 Horas<\/td><\/tr><\/tbody><\/table>                    <\/div>\n\t\t        \n                    <div id=\"unidades-didcticas-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"unidades-didcticas-tab\">\n\t\t\t\t        <style>.elementor-93117 .elementor-element.elementor-element-0cb1121{overflow:visible;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li i{font-size:16px;color:#333;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li img{width:16px;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li svg{width:16px;height:16px;fill:#333;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-tab-inline-icon li .title-before-icon{margin-right:10px;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-tab-inline-icon li .title-after-icon{margin-left:10px;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-tab-top-icon li i, .elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-tab-top-icon li img, .elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-tab-top-icon li svg{margin-bottom:10px;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li{background-color:#f1f1f1;color:#333;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li:hover{background-color:#333;color:#fff;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li:hover > i{color:#fff;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li:hover > svg{fill:#fff;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li.active{background-color:#444;color:#fff;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li.active > i{color:#fff;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li.active > svg{fill:#fff;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-content > div{color:#333;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs .eael-tabs-nav > ul li:after{border-width:10px;bottom:-10px;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs.eael-tabs-vertical > .eael-tabs-nav > ul li:after{right:-10px;top:calc(50% - 10px) !important;border-left-color:#444;}.rtl .elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs.eael-tabs-vertical > .eael-tabs-nav > ul li:after{right:auto;left:-10px !important;top:calc(50% - 10px) !important;}.elementor-93117 .elementor-element.elementor-element-b83e0e7 .eael-advance-tabs:not(.eael-tabs-vertical) > .eael-tabs-nav > ul li:after{border-top-color:#444;}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"93117\" class=\"elementor elementor-93117\">\n\t\t\t\t\t\t<section class=\"default no-position elementor-section elementor-top-section elementor-element elementor-element-0cb1121 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0cb1121\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfe359e\" data-id=\"bfe359e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b83e0e7 elementor-widget elementor-widget-eael-adv-tabs\" data-id=\"b83e0e7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"eael-adv-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div data-scroll-on-click=\"no\" data-scroll-speed=\"300\" id=\"eael-advance-tabs-b83e0e7\" class=\"eael-advance-tabs eael-tabs-vertical eael-tab-auto-active \" data-tabid=\"b83e0e7\">\n            <div class=\"eael-tabs-nav\">\n                <ul class=\"eael-tab-inline-icon\" role=\"tablist\">\n                                            <li id=\"i-semestre\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"i-semestre-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-folder-open\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >I Semestre<\/span>                            \n                                                    <\/li>\n                                            <li id=\"ii-semestre\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"ii-semestre-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-folder-open\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >II Semestre<\/span>                            \n                                                    <\/li>\n                                            <li id=\"iii-semestre\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"iii-semestre-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-folder-open\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >III Semestre<\/span>                            \n                                                    <\/li>\n                                            <li id=\"iv-semestre\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"iv-semestre-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-folder-open\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >IV Semestre<\/span>                            \n                                                    <\/li>\n                                            <li id=\"v-semestre\" class=\"inactive eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"v-semestre-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-folder-open\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >V Semestre<\/span>                            \n                                                    <\/li>\n                                            <li id=\"vi-semestre\" class=\" eael-tab-item-trigger eael-tab-nav-item\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"vi-semestre-tab\" aria-expanded=\"false\">\n                            \n                                                                <i class=\"fas fa-folder-open\"><\/i>                                                            \n                                                            <span class=\"eael-tab-title title-after-icon\" >VI Semestre<\/span>                            \n                                                    <\/li>\n                                    <\/ul>\n            <\/div>\n            \n            <div class=\"eael-tabs-content\">\n\t\t        \n                    <div id=\"i-semestre-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"i-semestre-tab\">\n\t\t\t\t        <table>\n<tbody>\n<tr>\n<th>N\u00ba<\/th>\n<th>Unidad Did\u00e1ctica<\/th>\n<th>N\u00ba Cr\u00e9ditos<\/th>\n<th>N\u00ba Horas<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">01<\/td>\n<td>Biolog\u00eda de Especies Acu\u00edcolas<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">02<\/td>\n<td>Manejo de Sistemas H\u00eddricos<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">04<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">03<\/td>\n<td>Poblaci\u00f3n de Especies Icticas<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">04<\/td>\n<td>Infraestructura Acu\u00edcola<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">05<\/td>\n<td>Salmonicultura<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr><th colspan=\"4\">Unidades de Empleabilidad<\/th><\/tr>\n<tr>\n<td style=\"text-align: center;\">06<\/td>\n<td>Comunicaci\u00f3n Interpersonal<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">07<\/td>\n<td>Aplicaciones en Internet<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<\/tbody>\n<\/table>                    <\/div>\n\t\t        \n                    <div id=\"ii-semestre-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"ii-semestre-tab\">\n\t\t\t\t        <table>\n<tbody>\n<tr>\n<th>N\u00ba<\/th>\n<th>Unidad Did\u00e1ctica<\/th>\n<th>N\u00ba Cr\u00e9ditos<\/th>\n<th>N\u00ba Horas<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">01<\/td>\n<td>Control Gen\u00e9tico Acu\u00edcola<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">02<\/td>\n<td>Control Sanitario<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">03<\/td>\n<td>Control Nutricional<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">04<\/td>\n<td>Producci\u00f3n Acu\u00edcola<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">05<\/td>\n<td>Cultivos Comerciales<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">06<\/td>\n<td>Salvataje en el Agua<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<th colspan=\"4\">Unidades de Empleabilidad<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">07<\/td>\n<td>Interpretaci\u00f3n y Producci\u00f3n de Textos<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">08<\/td>\n<td>Ofim\u00e1tica<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<\/tbody>\n<\/table>                    <\/div>\n\t\t        \n                    <div id=\"iii-semestre-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"iii-semestre-tab\">\n\t\t\t\t        <table>\n<tbody>\n<tr>\n<th>N\u00ba<\/th>\n<th>Unidad Did\u00e1ctica<\/th>\n<th>N\u00ba Cr\u00e9ditos<\/th>\n<th>N\u00ba Horas<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">01<\/td>\n<td>Limnolog\u00eda<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">02<\/td>\n<td>Evaluaci\u00f3n de Recursos Pesqueros<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">03<\/td>\n<td>Embarcaciones de Pesca<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">04<\/td>\n<td>Manejo de Equipos y Provisiones de Pesca<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">05<\/td>\n<td>Materiales y M\u00e9todos de Pesca<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">06<\/td>\n<td>Navegaci\u00f3n Pesquera<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<th colspan=\"4\">Unidades de Empleabilidad<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">07<\/td>\n<td>Comportamiento \u00c9tico<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">08<\/td>\n<td>Soluci\u00f3n de Problemas<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<\/tbody>\n<\/table>                    <\/div>\n\t\t        \n                    <div id=\"iv-semestre-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"iv-semestre-tab\">\n\t\t\t\t        <table>\n<tbody>\n<tr>\n<th>N\u00ba<\/th>\n<th>Unidad Did\u00e1ctica<\/th>\n<th>N\u00ba Cr\u00e9ditos<\/th>\n<th>N\u00ba Horas<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">01<\/td>\n<td>Sistemas Integrados de Gesti\u00f3n de Pesca<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">02<\/td>\n<td>Legislaci\u00f3n Pesquera<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">03<\/td>\n<td>Bioqu\u00edmica de Productos Hidrobiol\u00f3gicos<\/td>\n<td style=\"text-align: center;\">04<\/td>\n<td style=\"text-align: center;\">06<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">04<\/td>\n<td>Transporte de Productos Hidrobiol\u00f3gicos<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">05<\/td>\n<td>Gesti\u00f3n en Centros Acu\u00edcolas<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">06<\/td>\n<td>Comercializaci\u00f3n de Productos Hidrobiol\u00f3gicos<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<th colspan=\"4\">Unidades de Empleabilidad<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">07<\/td>\n<td>Innovaci\u00f3n Tecnol\u00f3gica<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<\/tbody>\n<\/table>                    <\/div>\n\t\t        \n                    <div id=\"v-semestre-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"v-semestre-tab\">\n\t\t\t\t        <table>\n<tbody>\n<tr>\n<th>N\u00ba<\/th>\n<th>Unidad Did\u00e1ctica<\/th>\n<th>N\u00ba Cr\u00e9ditos<\/th>\n<th>N\u00ba Horas<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">01<\/td>\n<td>Procesamiento Primario<\/td>\n<td style=\"text-align: center;\">04<\/td>\n<td style=\"text-align: center;\">06<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">02<\/td>\n<td>Procesamiento de Refrigeraci\u00f3n<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">03<\/td>\n<td>Procesamiento de Productos Curados<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">04<\/td>\n<td>Higiene y Seguridad Ocupacional en la Industria Pesquera<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">05<\/td>\n<td>Microbiolog\u00eda Pesquera<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<th colspan=\"4\">Unidades de Empleabilidad<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">06<\/td>\n<td>Ingles para la Comunicaci\u00f3n Oral<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">07<\/td>\n<td>Oportunidades de Negocio<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<\/tbody>\n<\/table>                    <\/div>\n\t\t        \n                    <div id=\"vi-semestre-tab\" class=\"clearfix eael-tab-content-item \" data-title-link=\"vi-semestre-tab\">\n\t\t\t\t        <table>\n<tbody>\n<tr>\n<th>N\u00ba<\/th>\n<th>Unidad Did\u00e1ctica<\/th>\n<th>N\u00ba Cr\u00e9ditos<\/th>\n<th>N\u00ba Horas<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">01<\/td>\n<td>Procesamiento de Pastas y Embutidos<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">02<\/td>\n<td>Procesamiento de Conservas<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">03<\/td>\n<td>Procesamiento de Ensilado, Harina y Aceite de Pescado<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">04<\/td>\n<td>Control de Calidad de Productos Pesqueros y Acu\u00edcolas<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<td style=\"text-align: center;\">05<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">05<\/td>\n<td>Envasados de Productos<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">06<\/td>\n<td>Maquinaria Pesquera de Envasado<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<th colspan=\"4\">Unidades de Empleabilidad<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">07<\/td>\n<td>Comprensi\u00f3n y Redacci\u00f3n en Ingles<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">08<\/td>\n<td>Planes de Negocio<\/td>\n<td style=\"text-align: center;\">02<\/td>\n<td style=\"text-align: center;\">03<\/td>\n<\/tr>\n<\/tbody>\n<\/table>                    <\/div>\n\t\t                    <\/div>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                    <\/div>\n\t\t        \n                    <div id=\"itinerario-formativo-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"itinerario-formativo-tab\">\n\t\t\t\t        <h4>ITINERARIO FORMATIVO &#8211; PROGRAMA DE ESTUDIOS DE: Desarrollo Pesquero y Acu\u00edcola<\/h4><p><img decoding=\"async\" src=\"https:\/\/iesjuli.edu.pe\/portal\/wp-content\/uploads\/2024\/10\/ITINERARIO-DE-DPA.png\" \/><\/p>                    <\/div>\n\t\t        \n                    <div id=\"horario-de-actividades-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"horario-de-actividades-tab\">\n\t\t\t\t        <p><span style=\"color: #000080;\"><strong>HORARIO ACAD\u00c9MICO:<\/strong><\/span><\/p><p style=\"padding-left: 40px;\"><span style=\"color: #000080;\">El IESTP JULI dispone de un horario general y de turno ma\u00f1ana. El horario general aplica a los seis (06) programas de estudios y a los seis semestres (I, II, III, IV, V, VI) acad\u00e9micos. La jornada acad\u00e9mica es de Lunes a Viernes de 8:00 a.m a 01:30 p.m.<\/span><\/p><p><span style=\"color: #000080;\"><strong>DISTRIBUCI\u00d3N DE HORAS:<\/strong><\/span><\/p><table><tbody><tr><td rowspan=\"9\" width=\"400\"><img decoding=\"async\" src=\"https:\/\/iesjuli.edu.pe\/portal\/wp-content\/uploads\/2024\/11\/logo_Juli.png\" \/><span style=\"color: #ffffff;\">HORAS<\/span><span style=\"color: #ffffff;\">DISTRIBUCI\u00d3N DE HORAS<\/span><\/td><\/tr><tr><td style=\"text-align: center;\"><span style=\"color: #000080;\">1\u00ba Hora<\/span><\/td><td style=\"text-align: center;\"><span style=\"color: #000080;\">08:00 a.m. &#8211; 08:45 a.m.<\/span><\/td><\/tr><tr><td style=\"text-align: center;\"><span style=\"color: #000080;\">2\u00ba Hora<\/span><\/td><td style=\"text-align: center;\"><span style=\"color: #000080;\">08:45 a.m. &#8211; 09:30 a.m.<\/span><\/td><\/tr><tr><td style=\"text-align: center;\"><span style=\"color: #000080;\">3\u00ba Hora<\/span><\/td><td style=\"text-align: center;\"><span style=\"color: #000080;\">09:30 a.m. &#8211; 10:15 a.m.<\/span><\/td><\/tr><tr><td style=\"text-align: center;\"><span style=\"color: #000080;\">4\u00ba Hora<\/span><\/td><td style=\"text-align: center;\"><span style=\"color: #000080;\">10:15 a.m. &#8211; 11:00 a.m.<\/span><\/td><\/tr><tr><th style=\"text-align: center;\" colspan=\"2\"><span style=\"color: #ffffff;\">RECESO<\/span><\/th><\/tr><tr><td style=\"text-align: center;\"><span style=\"color: #000080;\">5\u00ba Hora<\/span><\/td><td style=\"text-align: center;\"><span style=\"color: #000080;\">11:15 a.m. &#8211; 12:00 p.m.<\/span><\/td><\/tr><tr><td style=\"text-align: center;\"><span style=\"color: #000080;\">6\u00ba Hora<\/span><\/td><td style=\"text-align: center;\"><span style=\"color: #000080;\">12:00 p.m. &#8211; 12:45 p.m.<\/span><\/td><\/tr><tr><td style=\"text-align: center;\"><span style=\"color: #000080;\">7\u00ba Hora<\/span><\/td><td style=\"text-align: center;\"><span style=\"color: #000080;\">12:45 p.m. &#8211; 01:30 p.m.<\/span><\/td><\/tr><\/tbody><\/table>                    <\/div>\n\t\t        \n                    <div id=\"perfil-de-egreso-tab\" class=\"clearfix eael-tab-content-item inactive\" data-title-link=\"perfil-de-egreso-tab\">\n\t\t\t\t        <p style=\"text-align: justify;\"><span style=\"color: #000080;\">El profesional t\u00e9cnico del programa de estudios Desarrollo pesquero y acu\u00edcola, es competente en: Administrar los recursos requeridos en la unidad de embarcaci\u00f3n; Controlar par\u00e1metros del aspecto ambiental, de seguridad e inocuidad de los procesos y actividades de pesca; tambi\u00e9n, Dirigir las actividades de pesca; Implementar la infraestructura acu\u00edcola; Supervisar las actividades acu\u00edcolas; Ejecutar el tipo de procesamiento del recurso hidrobiol\u00f3gico e insumos; asi como, Ejecutar las operaciones de envasado, empaque y almacenamiento de los productos hidrobiol\u00f3gicos, piensos y producto veterinario de uso en acuicultura; y Establecer la log\u00edstica de distribuci\u00f3n de mercanc\u00edas considerando la cadena de fr\u00edo, puntos de comercializaci\u00f3n y normativa correspondiente; adem\u00e1s se comunica de manera efectiva, como tambi\u00e9n en idioma Ingles, utiliza tecnolog\u00edas de informaci\u00f3n, establece relaciones de respeto y justicia, soluciona problemas en su quehacer laboral, emprende proyectos innovadores relacionados a su actividad profesional y promueve el trabajo colaborativo.<\/span><\/p><p><strong><span style=\"color: #000080;\">\u00c1MBITO DE DESEMPE\u00d1O<\/span><\/strong><\/p><p><span style=\"color: #000080;\">El egresado puede desempe\u00f1arse en empresas, organizaciones e instituciones, p\u00fablicas y privadas, en las siguientes \u00e1reas:<\/span><\/p><ul><li><span style=\"color: #000080;\">\u00c1rea de embarcaciones.<\/span><\/li><li><span style=\"color: #000080;\">\u00c1rea de investigaci\u00f3n pesquera.<\/span><\/li><li><span style=\"color: #000080;\">\u00c1rea de producci\u00f3n acu\u00edcola.<\/span><\/li><li><span style=\"color: #000080;\">\u00c1rea de fiscalizaci\u00f3n pesquera.<\/span><\/li><li><span style=\"color: #000080;\">\u00c1rea de control acu\u00edcola.<\/span><\/li><li><span style=\"color: #000080;\">\u00c1rea de procesamiento de productos de consumos directo.<\/span><\/li><li><span style=\"color: #000080;\">\u00c1rea de procesamiento de productos de consumos indirecto.<\/span><\/li><li><span style=\"color: #000080;\">\u00c1rea de comercializaci\u00f3n de productos pesqueros.<\/span><\/li><\/ul>                    <\/div>\n\t\t                    <\/div>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n General M\u00f3dulos y Certificaciones Unidades Did\u00e1cticas Itinerario Formativo Horario de Actividades Perfil de Egreso COMPETENCIAS ESPEC\u00cdFICAS: Administrar los recursos requeridos en la unidad de embarcaci\u00f3n, de acuerdo con el tipo de especie a capturar, habitad acu\u00e1tico, embarcaci\u00f3n y normativa correspondiente. Controlar par\u00e1metros del aspecto ambiental, de seguridad e inocuidad de los procesos y actividades de pesca, de acuerdo con los sistemas integrados de gesti\u00f3n, est\u00e1ndares y normativa correspondiente. Dirigir las actividades de pesca de acuerdo con las funciones de la tripulaci\u00f3n, preservaci\u00f3n del recurso, \u00e1mbito acu\u00e1tico, seguridad de la embarcaci\u00f3n y normativa correspondiente. Implementar la infraestructura acu\u00edcola de acuerdo con las tecnolog\u00edas de cultivo, h\u00e1bitat acu\u00e1tico, condiciones sanitarias de las especies hidrobiol\u00f3gicas y normativa correspondiente. Supervisar las actividades acu\u00edcolas de acuerdo con las tecnolog\u00edas, especies hidrobiol\u00f3gicas, procedimientos establecidos y normativa correspondiente. Ejecutar el tipo de procesamiento del recurso hidrobiol\u00f3gico e insumos de acuerdo con el m\u00e9todo o tipo de operaci\u00f3n seleccionada, procedimientos establecidos y normativa correspondiente. Ejecutar las operaciones de envasado, empaque y almacenamiento de los productos hidrobiol\u00f3gicos, piensos y producto veterinario de uso en acuicultura considerando su trazabilidad, requerimientos tecnol\u00f3gicos del cliente, procedimientos establecidos y normativa correspondiente. Establecer la log\u00edstica de distribuci\u00f3n de mercanc\u00edas considerando la cadena de fr\u00edo, puntos de comercializaci\u00f3n y normativa correspondiente. T\u00cdTULO A NOMBRE DE LA NACI\u00d3N: Profesional T\u00e9cnico en Desarrollo Pesquero y Acu\u00edcola DURACI\u00d3N DE ESTUDIOS: 03 a\u00f1os (06 semestres acad\u00e9micos) MODALIDAD DE SERVICIO: Presencial. CERTIFICACIONES POR CADA M\u00d3DULO PROFESIONAL CERTIFICADO DENOMINACI\u00d3N DEL M\u00d3DULO DURACI\u00d3N SEMESTRE M\u00f3dulo N\u00b0 01: Implementaci\u00f3n y supervisi\u00f3n de sistemas de producci\u00f3n acu\u00edcola. 960 Horas I, II EFSRT 01: Experiencias Formativas en Situaciones Reales de Trabajo 128 Horas M\u00f3dulo N\u00b0 02: Administraci\u00f3n de recursos y direcci\u00f3n de actividades de pesca. 480 Horas III EFSRT 02: Experiencias Formativas en Situaciones Reales de Trabajo 64 Horas M\u00f3dulo N\u00b0 03: Control y log\u00edstica pesquera. 480 Horas IV EFSRT 03: Experiencias Formativas en Situaciones Reales de Trabajo 64 Horas M\u00f3dulo N\u00b0 04: Procesamiento y envasado de productos hidrobiol\u00f3gicos. 960 Horas V, VI EFSRT 04: Experiencias Formativas en Situaciones Reales de Trabajo 128 Horas I Semestre II Semestre III Semestre IV Semestre V Semestre VI Semestre N\u00ba Unidad Did\u00e1ctica N\u00ba Cr\u00e9ditos N\u00ba Horas 01 Biolog\u00eda de Especies Acu\u00edcolas 03 05 02 Manejo de Sistemas H\u00eddricos 03 04 03 Poblaci\u00f3n de Especies Icticas 03 05 04 Infraestructura Acu\u00edcola 03 05 05 Salmonicultura 03 05 Unidades de Empleabilidad 06 Comunicaci\u00f3n Interpersonal 02 03 07 Aplicaciones en Internet 02 03 N\u00ba Unidad Did\u00e1ctica N\u00ba Cr\u00e9ditos N\u00ba Horas 01 Control Gen\u00e9tico Acu\u00edcola 03 05 02 Control Sanitario 02 03 03 Control Nutricional 03 05 04 Producci\u00f3n Acu\u00edcola 03 05 05 Cultivos Comerciales 02 03 06 Salvataje en el Agua 02 03 Unidades de Empleabilidad 07 Interpretaci\u00f3n y Producci\u00f3n de Textos 02 03 08 Ofim\u00e1tica 02 03 N\u00ba Unidad Did\u00e1ctica N\u00ba Cr\u00e9ditos N\u00ba Horas 01 Limnolog\u00eda 03 05 02 Evaluaci\u00f3n de Recursos Pesqueros 02 03 03 Embarcaciones de Pesca 02 03 04 Manejo de Equipos y Provisiones de Pesca 02 03 05 Materiales y M\u00e9todos de Pesca 03 05 06 Navegaci\u00f3n Pesquera 03 05 Unidades de Empleabilidad 07 Comportamiento \u00c9tico 02 03 08 Soluci\u00f3n de Problemas 02 03 N\u00ba Unidad Did\u00e1ctica N\u00ba Cr\u00e9ditos N\u00ba Horas 01 Sistemas Integrados de Gesti\u00f3n de Pesca 03 05 02 Legislaci\u00f3n Pesquera 02 03 03 Bioqu\u00edmica de Productos Hidrobiol\u00f3gicos 04 06 04 Transporte de Productos Hidrobiol\u00f3gicos 02 03 05 Gesti\u00f3n en Centros Acu\u00edcolas 03 05 06 Comercializaci\u00f3n de Productos Hidrobiol\u00f3gicos 03 05 Unidades de Empleabilidad 07 Innovaci\u00f3n Tecnol\u00f3gica 02 03 N\u00ba Unidad Did\u00e1ctica N\u00ba Cr\u00e9ditos N\u00ba Horas 01 Procesamiento Primario 04 06 02 Procesamiento de Refrigeraci\u00f3n 03 05 03 Procesamiento de Productos Curados 03 05 04 Higiene y Seguridad Ocupacional en la Industria Pesquera 02 03 05 Microbiolog\u00eda Pesquera 03 05 Unidades de Empleabilidad 06 Ingles para la Comunicaci\u00f3n Oral 02 03 07 Oportunidades de Negocio 02 03 N\u00ba Unidad Did\u00e1ctica N\u00ba Cr\u00e9ditos N\u00ba Horas 01 Procesamiento de Pastas y Embutidos 03 05 02 Procesamiento de Conservas 03 05 03 Procesamiento de Ensilado, Harina y Aceite de Pescado 02 03 04 Control de Calidad de Productos Pesqueros y Acu\u00edcolas 03 05 05 Envasados de Productos 02 03 06 Maquinaria Pesquera de Envasado 02 03 Unidades de Empleabilidad 07 Comprensi\u00f3n y Redacci\u00f3n en Ingles 02 03 08 Planes de Negocio 02 03 ITINERARIO FORMATIVO &#8211; PROGRAMA DE ESTUDIOS DE: Desarrollo Pesquero y Acu\u00edcola HORARIO ACAD\u00c9MICO: El IESTP JULI dispone de un horario general y de turno ma\u00f1ana. El horario general aplica a los seis (06) programas de estudios y a los seis semestres (I, II, III, IV, V, VI) acad\u00e9micos. La jornada acad\u00e9mica es de Lunes a Viernes de 8:00 a.m a 01:30 p.m. DISTRIBUCI\u00d3N DE HORAS: HORASDISTRIBUCI\u00d3N DE HORAS 1\u00ba Hora 08:00 a.m. &#8211; 08:45 a.m. 2\u00ba Hora 08:45 a.m. &#8211; 09:30 a.m. 3\u00ba Hora 09:30 a.m. &#8211; 10:15 a.m. 4\u00ba Hora 10:15 a.m. &#8211; 11:00 a.m. RECESO 5\u00ba Hora 11:15 a.m. &#8211; 12:00 p.m. 6\u00ba Hora 12:00 p.m. &#8211; 12:45 p.m. 7\u00ba Hora 12:45 p.m. &#8211; 01:30 p.m. El profesional t\u00e9cnico del programa de estudios Desarrollo pesquero y acu\u00edcola, es competente en: Administrar los recursos requeridos en la unidad de embarcaci\u00f3n; Controlar par\u00e1metros del aspecto ambiental, de seguridad e inocuidad de los procesos y actividades de pesca; tambi\u00e9n, Dirigir las actividades de pesca; Implementar la infraestructura acu\u00edcola; Supervisar las actividades acu\u00edcolas; Ejecutar el tipo de procesamiento del recurso hidrobiol\u00f3gico e insumos; asi como, Ejecutar las operaciones de envasado, empaque y almacenamiento de los productos hidrobiol\u00f3gicos, piensos y producto veterinario de uso en acuicultura; y Establecer la log\u00edstica de distribuci\u00f3n de mercanc\u00edas considerando la cadena de fr\u00edo, puntos de comercializaci\u00f3n y normativa correspondiente; adem\u00e1s se comunica de manera efectiva, como tambi\u00e9n en idioma Ingles, utiliza tecnolog\u00edas de informaci\u00f3n, establece relaciones de respeto y justicia, soluciona problemas en su quehacer laboral, emprende proyectos innovadores relacionados a su actividad profesional y promueve el trabajo colaborativo. \u00c1MBITO DE DESEMPE\u00d1O El egresado puede desempe\u00f1arse en empresas, organizaciones e instituciones, p\u00fablicas y privadas, en las siguientes \u00e1reas: \u00c1rea de embarcaciones. \u00c1rea de investigaci\u00f3n pesquera. \u00c1rea de producci\u00f3n acu\u00edcola.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2263","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/pages\/2263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/comments?post=2263"}],"version-history":[{"count":59,"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/pages\/2263\/revisions"}],"predecessor-version":[{"id":95456,"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/pages\/2263\/revisions\/95456"}],"wp:attachment":[{"href":"https:\/\/iesjuli.edu.pe\/portal\/wp-json\/wp\/v2\/media?parent=2263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}